{"id":6383,"date":"2019-05-21T08:33:23","date_gmt":"2019-05-21T06:33:23","guid":{"rendered":"https:\/\/voice.global\/?p=6383"},"modified":"2019-05-21T10:50:10","modified_gmt":"2019-05-21T08:50:10","slug":"fail-fair-au-mali","status":"publish","type":"post","link":"https:\/\/voice.global\/fr\/fail-fair-au-mali\/","title":{"rendered":"Fail Fair au Mali!"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">La foire de l\u2019\u00e9chec fut un succ\u00e8s  <\/h2>\n\n\n\n<p><em>Ecrit par Kadida Tangara, Responsable de Communications, <a href=\"https:\/\/voice.global\/fr\/partenaires\/connecter-voix-mali-niger\/\">Accountability Lab<\/a>, Facilitateur de Lien et Apprentissage, Mali<\/em><\/p>\n\n\n\n<p>Que d\u2019\u00e9motions, entre la joie de vivre, la frustration, la tristesse, le bonheur et m\u00eame des pas de danse. Autant d\u2019\u00e9l\u00e9ments constituant cette belle journ\u00e9e du Fail Fair. Premier du genre au Mali dans le cadre de Voice, la salle de la maison de la Femme et de la Famille \u00e9tait tr\u00e8s anim\u00e9e ce samedi 27 avril 2019. <\/p>\n\n\n\n<p>Six pan\u00e9listes dont trois femmes et trois hommes. Tous ont un point commun, vivre avec le handicap. Il s\u2019agit de premierement Niama Kon\u00e9, Amadou Demb\u00e9l\u00e9, Kadiatou Coulibaly dite Katoucha, Sidiki dit Latiki Kouma, Filifing Sidib\u00e9 et Dr Abdoulaye Diallo. A travers des t\u00e9moignages remplis d\u2019\u00e9motions, de courage et de pers\u00e9v\u00e9rance, le publique a compris que l\u2019\u00e9chec est une partie int\u00e9grante du succ\u00e8s.  <\/p>\n\n\n\n<blockquote style=\"text-align:center\" class=\"wp-block-quote is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p>   \u00ab\u00a0<em>On vous pr\u00e9sente les six portraits \u00e9mouvants!<\/em>\u00ab\u00a0<\/p><\/blockquote>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"826\" src=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Niama-Kone-1024x826.jpg\" alt=\"\" class=\"wp-image-6392\" srcset=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Niama-Kone-1024x826.jpg 1024w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Niama-Kone-300x242.jpg 300w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Niama-Kone-768x619.jpg 768w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Niama-Kone-415x336.jpg 415w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Vivant avec l\u2019albinisme, Niama Kone est issue d\u2019une famille nombreuse comptant deux personnes vivants avec l\u2019albinisme. Niama a toujours nourri un r\u00eave d\u2019aller travailler pour la poste. Elle a int\u00e9gr\u00e9 l\u2019\u00c9cole Nationale des Postes o\u00f9 elle a obtenu un dipl\u00f4me de contr\u00f4leur du service g\u00e9n\u00e9ral en 1989 et la m\u00eame ann\u00e9e, elle a d\u00e9croch\u00e9 le concours d\u2019entr\u00e9e \u00e0 la Fonction Publique. Actuellement, elle est Chef Poste en Qualit\u00e9 au sein de la Direction G\u00e9n\u00e9rale de la Poste et pr\u00e9sidente du conseil d\u2019Administration d\u2019Accountability Lab Mali. <\/p>\n\n\n\n<p>Une femme int\u00e8gre et surtout d\u00e9vou\u00e9e \u00e0 servir son pays, Niama affirme que son papa lui disait&nbsp;toujours de ne pas s\u2019isoler, \u00e0 cause de son handicap. Elle a donc grandi avec cette id\u00e9e dans la t\u00eate, et l\u2019albinisme n\u2019est pas un frein pour elle. Plusieurs fois victime d\u2019actes de sabotage de la part de ses coll\u00e8gues, Mme Kon\u00e9 arrive toujours \u00e0 se relever. L\u2019\u00e9chec n\u2019est pas de tomber, mais de refuser de se lever.  Elle a r\u00e9ussi deux fois le concours\ndes inspecteurs, elle est m\u00eame arriv\u00e9e en t\u00eate, mais malheureusement \u00e0 cause des\nfalsifications des r\u00e9sultats son nom n\u2019apparait jamais sur la liste. Malgr\u00e9 le fait qu\u2019elle a \u00e9t\u00e9 victime\nde malversations, tr\u00e8s d\u00e9termin\u00e9e, en 2008, elle a pass\u00e9 le concours au S\u00e9n\u00e9gal\net cette fois ci \u00e7a a march\u00e9. <\/p>\n\n\n\n<p>Tr\u00e8s int\u00e8gre et syndicaliste (parce qu\u2019elle aime d\u00e9fendre les droits des travailleurs), Niama pense que, seul le travail bien fait valorise l\u2019homme. Pour elle la patience finit toujours par payer.  Une femme tr\u00e8s calme. On lui a souvent dit qu\u2019elle ne sera jamais inspecteur (soit une promotion professionnelle). Malgr\u00e9 les d\u00e9couragements et les tentatives de sabotages, cela ne l\u2019a pas arr\u00eat\u00e9. Aujourd\u2019hui elle est cheffe de service \u00e0 la poste. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"826\" src=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-GADEC-1024x826.jpg\" alt=\"\" class=\"wp-image-6386\" srcset=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-GADEC-1024x826.jpg 1024w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-GADEC-300x242.jpg 300w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-GADEC-768x619.jpg 768w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-GADEC-415x336.jpg 415w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Avant de voir sa taille, c\u2019est son sourire qu\u2019on aper\u00e7oit en premier lieu. Amadou Dembele est une personne de petite taille. \u00c2g\u00e9 de 27 ans, il mesure 84 centim\u00e8tres pour 35 kilos. N\u00e9 \u00e0 Zantiguila, dans le Cercle de Sikasso, Amadou n\u2019a pas eu une enfance facile. Sa vie va basculer \u00e0 la mort de ses parents quant il \u00e9tait encore un enfant.&nbsp; Pendant des ann\u00e9es il a v\u00e9cu de la mendicit\u00e9. Son marabout l\u2019a encourag\u00e9 \u00e0 mendier car il ne pouvait pas travailler, pourtant sa situation ne lui permettait pas de marcher de longue distance. Par la suite, il est rest\u00e9 dans la maison du marabout pour \u00e9tudier le coran.<\/p>\n\n\n\n<p>Discrimin\u00e9 par sa taille, les personnes ne lui donnaient pas grand chose. Pour eux il n\u2019\u00e9tait pas une personne normale. Certains m\u00eame le traitait de monstre. Grace \u00e0 l\u2019assistance de l\u2019ONG <a href=\"https:\/\/voice.global\/fr\/partenaires\/handicap-mode-et-art\/\">GADEC<\/a>, partenaire de Voice \u00e0 S\u00e9gou, Amadou est maintenant un grand musicien. Il joue et danse sur les rythmes du balafon, un instrument de percussion originaire du Mali. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"826\" src=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Kadiatou-1024x826.jpg\" alt=\"\" class=\"wp-image-6388\" srcset=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Kadiatou-1024x826.jpg 1024w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Kadiatou-300x242.jpg 300w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Kadiatou-768x619.jpg 768w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Kadiatou-415x336.jpg 415w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Commun\u00e9ment appel\u00e9e Katoucha, Kadiatou Coulibaly est une femme battante vivant avec le handicap. N\u00e9e en 1977 \u00e0 Bamako, Katoucha est une m\u00e8re c\u00e9libataire. Actuellement elle est entrepreneuse, po\u00e8te et secr\u00e9taire g\u00e9n\u00e9rale adjointe du bureau ex\u00e9cutif de l\u2019Union Malienne des Associations et Comit\u00e9s des Femmes Handicap\u00e9es (<a href=\"https:\/\/voice.global\/fr\/partenaires\/entreprenariat-et-handicap-encadrement-des-femmes-entrepreneures-handicapees\/\">UMAPH<\/a>), aussi un partenaire de Voice. Issue d\u2019une famille pauvre, \u00e0 l\u2019\u00e2ge\nde 3 ans, elle fut atteinte de la poliomy\u00e9lite, infection virale tr\u00e8s\ncontagieuse touchant principalement les enfants pouvant entrainer une paralysie\nirr\u00e9versible. Ses parents ont tout fait pour\nl\u2019inscrire \u00e0 l\u2019\u00e9cole. C\u2019est seulement \u00e0 l\u2019\u00e2ge de de 8 ans qu\u2019elle y fait ses\npremiers pas, son p\u00e8re avait peur qu\u2019elle ne soit une victime ou un bouc\n\u00e9missaire. <\/p>\n\n\n\n<p>L\u2019ann\u00e9e de son bac en 1999, elle est tomb\u00e9e enceinte et elle accoucha juste avant les examens. Se pr\u00e9sentant \u00e0 ses examens avec les fraiches cicatrices de sa c\u00e9sarienne. Apr\u00e8s son examen, elle d\u00e9cida d\u2019abandonner l\u2019\u00e9cole. Plusieurs facteurs de d\u00e9couragement l\u2019ont fait prendre cette dure d\u00e9cision tels que le fait qu\u2019elle soit m\u00e8re d\u2019un jeune enfant, la distance de l\u2019\u00e9cole et l\u2019abandon du p\u00e8re de l\u2019enfant.  D\u00e9gout\u00e9e de la vie, Katoucha a eu\nun jour fortement penser au suicide pour en finir avec toutes ces souffrances.&nbsp;Mais\nson amour pour ses parents et pour son fils l\u2019a aid\u00e9 \u00e0 tenir. Avec l\u2019aide et le conseil d\u2019une\nbrave dame, Kadiatou retourna \u00e0 l\u2019\u00e9cole pour \u00e9tudier la gestion des ressources\nhumaines en cours du soir \u00e0 l\u2019IUG, et cela apr\u00e8s 19 ann\u00e9es d\u2019absence sur les\nbancs de l\u2019\u00e9cole. <\/p>\n\n\n\n<p>Selon elle, la premi\u00e8re \u00e9tape du\nsucc\u00e8s est la confiance en soi.<\/p>\n\n\n\n<p>Actuellement Katoucha a mont\u00e9 sa propre entreprise et elle a plusieurs projets en vu notamment la r\u00e9alisation de po\u00e8mes pour encourager les personnes marginalis\u00e9es \u00e0 aller de l\u2019avant. Survivante, battante, brave, courageuse et travailleuse\u2026. Pour Katoucha l\u2019\u00e9chec est une partie int\u00e9grante du succ\u00e8s. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"826\" src=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Latiki-Sidiki-1024x826.jpg\" alt=\"\" class=\"wp-image-6390\" srcset=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Latiki-Sidiki-1024x826.jpg 1024w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Latiki-Sidiki-300x242.jpg 300w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Latiki-Sidiki-768x619.jpg 768w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Latiki-Sidiki-415x336.jpg 415w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Tr\u00e8s intelligent,\ndepuis \u00e0 bas \u00e2ge, le p\u00e8re de Sidiki Latiki Kouma d\u00e9c\u00e8de en avril 2018, lui a\ninculqu\u00e9 des valeurs qui resteront grav\u00e9 en lui. &nbsp;N\u00e9 en 1989 \u00e0 Bamako. Sidiki est\noriginaire de Sizani dans la r\u00e9gion de S\u00e9gou. A l\u2019\u00e2ge de 4 ans, il a \u00e9t\u00e9\nenvoyer au village pour apprendre le coran. &nbsp;Un retour aux sources, qui lui a\npermis d\u2019en apprendre plus sur sa culture et d\u2019avoir de fortes racines pour\nmieux d\u00e9coller. <\/p>\n\n\n\n<p>Sidiki se sent \u00e0 l\u2019aise avec son handicap, il l\u2019accepte pleinement nous dit-il en souriant. <strong>Sachez qu\u2019un homme c\u2019est sa t\u00eate !<\/strong> Voil\u00e0 ce que son p\u00e8re lui avait dit et qu\u2019il n\u2019oubliera jamais. La vie de Sidiki a bascul\u00e9 apr\u00e8s la\ns\u00e9paration de ses parents. Pour lui ce fut son premier \u00e9chec&nbsp;puis l\u2019\u00e9chec\nau bac s\u00e9rie Sciences Exactes. <\/p>\n\n\n\n<blockquote style=\"text-align:center\" class=\"wp-block-quote is-style-large is-layout-flow wp-block-quote-is-layout-flow\"><p> \u00ab&nbsp;Bien vrai que mes camarades et enseignants me regardaient bizarrement comme si j\u2019\u00e9tait un animal, j\u2019ai toujours \u00e9t\u00e9 le premier de la classe. Et mon p\u00e8re ne m\u2019a jamais demand\u00e9 de r\u00e9viser mes le\u00e7ons \u00bb. <\/p><\/blockquote>\n\n\n\n<p>Un homme extr\u00eamement intelligent, qui a connu beaucoup d\u2019\u00e9chec d\u2019ordre acad\u00e9mique. Malgr\u00e9 tout cela, il a persist\u00e9 et il n\u2019a pas abandonn\u00e9e. Aujourd\u2019hui il est \u00e9tudiant en 4<sup>\u00e8me<\/sup> ann\u00e9e finance comptabilit\u00e9 au Centre d\u2019Industrie et de Gestion(C.I.GES), Latiki fait partie de plusieurs mouvements associatifs, entre autres le Mouvement Jeunesse Avenir (M.J.A-Mali) ; l\u2019AJCAD-Mali (Association des Jeunes pour la Citoyennet\u00e9 Active et la D\u00e9mocratie)&nbsp;; l\u2019ANJLM (Association Nationale des Jeunes Lecteurs du Mali) pour la promotion des \u00e9crivains, etc. Amoureux de la po\u00e9sie, son r\u00eave\n\u00e9tait d\u2019appartenir au monde des \u00e9crivains. Il vit son r\u00eave ! <\/p>\n\n\n\n<p>En septembre 2015, il fut 3<sup>\u00e8me<\/sup> au concours national \u00ab&nbsp;Transcrire la m\u00e9moire de notre soci\u00e9t\u00e9\u2019&nbsp;\u00bb, organis\u00e9 par le Centre PEN-Mali et le Mouvement Mali-valeurs \u00e0 l\u2019issue duquel son tout premier<strong> <\/strong>ouvrage intitul\u00e9 \u00ab&nbsp;La culture de chez nous&nbsp;\u00bb fut prim\u00e9 avec le Prix Bakari KAMIAN \u00e9dit\u00e9 par la maison d\u2019\u00e9dition \u00ab&nbsp;La Sah\u00e9lienne&nbsp;\u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"826\" src=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Sidibe-1024x826.jpg\" alt=\"\" class=\"wp-image-6394\" srcset=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Sidibe-1024x826.jpg 1024w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Sidibe-300x242.jpg 300w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Sidibe-768x619.jpg 768w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Sidibe-415x336.jpg 415w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Filyfing Sidib\u00e9 a eu son handicap \u00e0\nl\u2019enfance quand elle s\u00e9journait en C\u00f4te d\u2019Ivoire chez sa tante. Tr\u00e8s marginalis\u00e9e\npar cette derni\u00e8re et sa famille, elle n\u2019a pas eu la chance d\u2019\u00eatre soigner \u00e0\ntemps. Toujours cach\u00e9e dans sa chambre, Filyfing\navait peur du regard des hommes. Enceint\u00e9e tr\u00e8s jeune par son voisin du quartier,\nle p\u00e8re de l\u2019enfant d\u00e9c\u00e9da au troisi\u00e8me mois de sa grossesse. Apr\u00e8s son d\u00e9c\u00e8s,\nla famille a refus\u00e9 de reconnaitre sa grossesse affirmant que leur fils n\u2019avait\naucun int\u00e9r\u00eat \u00e0 \u00eatre avec une personne handicap\u00e9e.<\/p>\n\n\n\n<p>Apr\u00e8s son retour au Mali, Filyfing a\nconnu un grand soutien en sa grande s\u0153ur qui lui disait toujours qu\u2019elle\npouvait TOUT faire. Ces mots d\u2019encouragement lui ont permis d\u2019ouvrir son propre\n\u00e9tablissement de restauration \u00e0 Kati. Aujourd\u2019hui Filyfing m\u00e8ne plusieurs\nactivit\u00e9s g\u00e9n\u00e9ratrices de revenus pour subvenir \u00e0 ses besoins. <\/p>\n\n\n\n<p>\u00ab&nbsp;Nous sommes tous pareils, certes dieu m\u2019a retir\u00e9 quelque chose mais il ne m\u2019a pas tout retir\u00e9, je vois, j\u2019entends et je suis en mesure d\u2019utiliser mes bras&nbsp;\u00bb. &nbsp;Le handicap n\u2019est pas un frein pour Filyfing et surtout pas le synonyme de la mendicit\u00e9.  Pour elle, seul le travail paie ! Son exp\u00e9rience est un r\u00e9el espoir pour toutes les personnes \u00e0 la recherche d\u2019emploi, vivant avec un handicap ou non, car le monde est rempli de possibilit\u00e9s. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"826\" src=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Abdoulaye-1024x826.jpg\" alt=\"\" class=\"wp-image-6384\" srcset=\"https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Abdoulaye-1024x826.jpg 1024w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Abdoulaye-300x242.jpg 300w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Abdoulaye-768x619.jpg 768w, https:\/\/voice.global\/assets\/2019\/05\/Accountability-Lab-Abdoulaye-415x336.jpg 415w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Un homme \u00e2g\u00e9 mais dot\u00e9 d\u2019une\nm\u00e9moire exceptionnelle, Dr Abdoulaye Diallo racontes ses v\u00e9cues avec un sens du\nd\u00e9tail tr\u00e8s aiguis\u00e9 !Souvent qualifi\u00e9 de surdou\u00e9, Dr\nDiallo voit sa vision s\u2019affaiblir \u00e0 l\u2019adolescence. Ne pouvant plus \u00e9tudier il a\npr\u00e9f\u00e9r\u00e9 cacher sa maladie \u00e0 ses parents de peur qu\u2019ils soient abattus en\napprenant la nouvelle.&nbsp; Avec 1500 FCFA en\npoche, il d\u00e9cida de partir \u00e0 l\u2019aventure au S\u00e9n\u00e9gal. Apr\u00e8s avoir accumul\u00e9 plusieurs\npetits boulots au S\u00e9n\u00e9gal et en Gambie, il revient au Mali en 1977 pour\neffectuer son baccalaur\u00e9at, apr\u00e8s avoir entendu qu\u2019une organisation aident les\npersonnes aveugles. Premier bachelier non voyant, Dr Abdoulaye Diallo n\u2019a pas\npu int\u00e9grer l\u2019universit\u00e9 pour poursuivre ses \u00e9tudes. Bloqu\u00e9 pendant 3 ans pour\ndes raisons n\u00e9buleuses, il a \u00e9t\u00e9 forc\u00e9 de se convertir en professeur de 2<sup>nd<\/sup>\ncycle. <\/p>\n\n\n\n<p>Pour Dr Diallo ses \u00e9checs ne l\u2019ont jamais d\u00e9courag\u00e9, car sa force int\u00e9rieure lui disait toujours qu\u2019il \u00e9tait capable d\u2019atteindre ses objectifs.Par ces bravoures, il a obtenu une bourse d\u2019\u00e9tude de la m\u00e9decine en Tunisie. A son retour il a construit un h\u00f4pital de soin m\u00e9dicaux au sein de l\u2019<a href=\"https:\/\/voice.global\/fr\/partenaires\/inclusion-socio-economique-et-politique-des-personnes-handicapees\/\">UMAV<\/a> (Union Malienne des Aveugles), un partenaire de Voice. Actuellement son cabinet de kin\u00e9sith\u00e9rapeute conna\u00eet un fort succ\u00e8s et ses ordonnances en braille sont accept\u00e9s par de nombreuses pharmacies. &nbsp;<\/p>\n\n\n\n<p>Selon Dr Abdoulaye Diallo, il faut toujours avoir foi en ses objectifs ! D\u2019ailleurs ses enfants se sont inspir\u00e9s de sa pers\u00e9v\u00e9rance et de son courage, trois d\u2019entre eux sont m\u00e9decins. <\/p>\n\n\n\n<p>En conclusion, de nombreuses personnes peuvent penser qu\u2019\u00eatre en fauteuil roulant, \u00eatre une personne vivant avec l\u2019albinisme, \u00eatre mal voyant ou mal entendant est synonyme de tristesse. Mais \u00e0 travers les t\u00e9moignages de nos six pan\u00e9listes de la premi\u00e8re \u00e9dition du Fail Fair (foire de l\u2019\u00e9chec) de VOice, le public malien a compris que nous vivons tous des d\u00e9fis dans nos vies respectives. Le handicap n\u2019est pas une fatalit\u00e9, il s\u2019agit seulement d\u2019une diff\u00e9rence visible mais qui n\u2019emp\u00eache pas \u00e0 tout un chacun de r\u00e9aliser ses r\u00eaves. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>La foire de l\u2019\u00e9chec fut un succ\u00e8s Ecrit par Kadida Tangara, Responsable de Communications, Accountability Lab, Facilitateur de Lien et Apprentissage, Mali Que d\u2019\u00e9motions, entre la joie de vivre, la frustration, la tristesse, le bonheur et m\u00eame des pas de danse. Autant d\u2019\u00e9l\u00e9ments constituant cette belle journ\u00e9e du Fail Fair. Premier du genre au Mali [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":6406,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"country-cat":[],"class_list":["post-6383","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee"],"thumbnail_src":"https:\/\/voice.global\/assets\/2019\/05\/Announcement-Fail-Fair.jpg","_links":{"self":[{"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/posts\/6383","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/comments?post=6383"}],"version-history":[{"count":5,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/posts\/6383\/revisions"}],"predecessor-version":[{"id":6419,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/posts\/6383\/revisions\/6419"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/media\/6406"}],"wp:attachment":[{"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/media?parent=6383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/categories?post=6383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/tags?post=6383"},{"taxonomy":"country-cat","embeddable":true,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/country-cat?post=6383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}