{"id":13261,"date":"2021-03-02T07:58:19","date_gmt":"2021-03-02T06:58:19","guid":{"rendered":"https:\/\/voice.global\/5years\/magic-moment-tien\/"},"modified":"2021-03-18T11:53:14","modified_gmt":"2021-03-18T10:53:14","slug":"magique-moment-tien","status":"publish","type":"5years","link":"https:\/\/voice.global\/fr\/5years\/magique-moment-tien\/","title":{"rendered":"Thuy Tien"},"content":{"rendered":"\n<p>Quel est mon moment magique ? Je me souviens de la fois o\u00f9 j&rsquo;ai particip\u00e9 au Concours NOW-Us !2018 aux Pays-Bas et j&rsquo;ai beaucoup appris de ces prix. Apr\u00e8s \u00eatre rentr\u00e9e au Vietnam avec le projet de subvention de Voice, nous avons travaill\u00e9 ensemble sur le voyage d&rsquo;autonomisation de la communaut\u00e9 des sourds. Nous avons appliqu\u00e9 notre exp\u00e9rience et nos connaissances \u00e0 l&rsquo;organisation du concours NOW-Deaf ! au Vietnam. C&rsquo;est alors que la magie s&rsquo;est mise en marche ! Je suis si fi\u00e8re de voir les jeunes sourds exprimer avec confiance leurs d\u00e9fis, en proposant des solutions et des initiatives pour leurs communaut\u00e9s. C&rsquo;est l&rsquo;esprit de Nothing about Deaf without Deaf ou Rien sur des Sourds, sans Sourds. Je crois que la magie se r\u00e9pand de plus en plus, qu&rsquo;elle continue \u00e0 avoir un impact sur la prochaine g\u00e9n\u00e9ration et qu&rsquo;elle d\u00e9veloppe notre communaut\u00e9 de sourds.<\/p>\n\n\n\n<p>C&rsquo;est mon voyage magique !<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La magie de Tien est apparue lorsqu&rsquo;elle est rentr\u00e9e chez elle apr\u00e8s le NoW-Us ! et elle a organis\u00e9 le concours Nothing about the Deaf without the Deaf (Rien sur les Sourds sans les Sourds) au Vietnam.<\/p>\n","protected":false},"featured_media":13197,"template":"","five-year-country":[],"five-year-organization":[385],"fatuma":[],"class_list":["post-13261","5years","type-5years","status-publish","has-post-thumbnail","hentry","five-year-organization-grantees-fr"],"_links":{"self":[{"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/5years\/13261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/5years"}],"about":[{"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/types\/5years"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/media\/13197"}],"wp:attachment":[{"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/media?parent=13261"}],"wp:term":[{"taxonomy":"five-year-country","embeddable":true,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/five-year-country?post=13261"},{"taxonomy":"five-year-organization","embeddable":true,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/five-year-organization?post=13261"},{"taxonomy":"fatuma","embeddable":true,"href":"https:\/\/voice.global\/fr\/wp-json\/wp\/v2\/fatuma?post=13261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}